{"id":250,"date":"2026-01-15T16:46:47","date_gmt":"2026-01-15T16:46:47","guid":{"rendered":"https:\/\/thomasgianola.com\/?page_id=250"},"modified":"2026-02-18T16:24:53","modified_gmt":"2026-02-18T16:24:53","slug":"guida-alpina-dolomiti","status":"publish","type":"page","link":"https:\/\/thomasgianola.com\/it\/","title":{"rendered":"Guida alpina Dolomiti"},"content":{"rendered":"[et_pb_section fb_built=\u201c1\u2033 fullwidth=\u201con\u201c admin_label=\u201cHero\u201c _builder_version=\u201c4.16\u2033 background_color=\u201c#233b4e\u201c parallax=\u201con\u201c custom_padding=\u201c0px|0px|0px|0px\u201c global_colors_info=\u201c{}\u201c][et_pb_fullwidth_header title=\u201cTHomas Gianola Bergf\u00fchrer\u201c subhead=\u201cGEF\u00dcHRTE BERG- UND KLETTERTOUREN IN DEN DOLOMITEN UND DEN ALPEN\u201c button_one_text=\u201ckontakt\u201c button_one_url=\u201cthomasgianola.com\/kontakt\u201c background_overlay_color=\u201crgba(29,38,51,0.86)\u201c content_max_width=\u201c700px\u201c admin_label=\u201cHero Section\u201c _builder_version=\u201c4.27.5\u2033 title_font=\u201cOswald|on||on|\u201c title_font_size=\u201c54px\u201c title_line_height=\u201c1.3em\u201c content_font=\u201cRoboto||||\u201c content_font_size=\u201c20px\u201c background_color=\u201crgba(255, 255, 255, 0)\u201c background_image=\u201chttp:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Eisklettern-Cerro-Torre-Thomas-Gianola-Bergfuehrer.jpg\u201c custom_button_one=\u201con\u201c button_one_border_radius=\u201c0px\u201c button_one_letter_spacing=\u201c4px\u201c button_one_font=\u201cOswald|on||on|\u201c button_one_icon=\u201c$||divi||400\u2033 button_one_icon_color=\u201c#ffffff\u201c custom_margin=\u201c|||\u201c custom_padding=\u201c150px||150px|\u201c custom_padding_tablet=\u201c60px||60px|\u201c custom_padding_phone=\u201c\u201c custom_padding_last_edited=\u201con|tablet\u201c animation_style=\u201czoom\u201c animation_direction=\u201cbottom\u201c animation_intensity_zoom=\u201c4%\u201c button_one_text_color_hover=\u201c#ffffff\u201c button_one_border_color_hover=\u201c#ffffff\u201c button_one_border_radius_hover=\u201c0px\u201c button_one_letter_spacing_hover=\u201c4px\u201c button_one_bg_color_hover=\u201crgba(0,0,0,0)\u201c global_colors_info=\u201c{}\u201c button_one_text_size__hover_enabled=\u201coff\u201c button_two_text_size__hover_enabled=\u201coff\u201c button_one_text_color__hover_enabled=\u201con\u201c button_one_text_color__hover=\u201c#ffffff\u201c button_two_text_color__hover_enabled=\u201coff\u201c button_one_border_width__hover_enabled=\u201coff\u201c button_two_border_width__hover_enabled=\u201coff\u201c button_one_border_color__hover_enabled=\u201con\u201c button_one_border_color__hover=\u201c#ffffff\u201c button_two_border_color__hover_enabled=\u201coff\u201c button_one_border_radius__hover_enabled=\u201con\u201c button_one_border_radius__hover=\u201c0px\u201c button_two_border_radius__hover_enabled=\u201coff\u201c button_one_letter_spacing__hover_enabled=\u201con\u201c button_one_letter_spacing__hover=\u201c4px\u201c button_two_letter_spacing__hover_enabled=\u201coff\u201c button_one_bg_color__hover_enabled=\u201con\u201c button_one_bg_color__hover=\u201crgba(0,0,0,0)\u201c button_two_bg_color__hover_enabled=\u201coff\u201c][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u201c1\u2033 admin_label=\u201cGallery\u201c _builder_version=\u201c4.16\u2033 custom_padding=\u201c0px||0px|\u201c global_colors_info=\u201c{}\u201c][et_pb_row column_structure=\u201c1_4,1_4,1_4,1_4\u2033 use_custom_gutter=\u201con\u201c gutter_width=\u201c1\u2033 make_equal=\u201con\u201c module_class=\u201cfour-columns\u201c _builder_version=\u201c4.27.5\u2033 width=\u201c100%\u201c width_tablet=\u201c100%\u201c width_phone=\u201c100%\u201c width_last_edited=\u201con|desktop\u201c max_width=\u201c100%\u201c max_width_tablet=\u201c100%\u201c max_width_phone=\u201c100%\u201c max_width_last_edited=\u201con|desktop\u201c custom_padding=\u201c0px|0px|0px|0px\u201c make_fullwidth=\u201con\u201c global_colors_info=\u201c{}\u201c][et_pb_column type=\u201c1_4\u2033 _builder_version=\u201c4.16\u2033 custom_padding=\u201c|||\u201c global_colors_info=\u201c{}\u201c custom_padding__hover=\u201c|||\u201c][et_pb_image src=\u201chttps:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Klettern-Arco-gardasee-Bergfuehrer.webp\u201c alt=\u201cKlettern am Gardasee mit Bergf\u00fchrer Arco\u201c title_text=\u201cKlettern Arco gardasee Bergf\u00fchrer\u201c show_in_lightbox=\u201con\u201c force_fullwidth=\u201con\u201c align_tablet=\u201ccenter\u201c align_phone=\u201ccenter\u201c align_last_edited=\u201con|desktop\u201c _builder_version=\u201c4.27.5\u2033 animation_style=\u201czoom\u201c animation_direction=\u201cleft\u201c animation_duration=\u201c500ms\u201c animation_intensity_zoom=\u201c10%\u201c global_colors_info=\u201c{}\u201c][\/et_pb_image][\/et_pb_column][et_pb_column type=\u201c1_4\u2033 _builder_version=\u201c4.16\u2033 custom_padding=\u201c|||\u201c global_colors_info=\u201c{}\u201c custom_padding__hover=\u201c|||\u201c][et_pb_image src=\u201chttps:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Plattkofel-Klettern-Dolomiten.webp\u201c alt=\u201cKlettern Dolomiten Klassiker Plattkofel Gr\u00f6den\u201c title_text=\u201cPlattkofel Klettern Dolomiten\u201c show_in_lightbox=\u201con\u201c force_fullwidth=\u201con\u201c align_tablet=\u201ccenter\u201c align_phone=\u201ccenter\u201c align_last_edited=\u201con|desktop\u201c _builder_version=\u201c4.27.5\u2033 animation_style=\u201czoom\u201c animation_direction=\u201cleft\u201c animation_duration=\u201c500ms\u201c animation_delay=\u201c100ms\u201c animation_intensity_zoom=\u201c10%\u201c locked=\u201coff\u201c global_colors_info=\u201c{}\u201c][\/et_pb_image][\/et_pb_column][et_pb_column type=\u201c1_4\u2033 _builder_version=\u201c4.16\u2033 custom_padding=\u201c|||\u201c global_colors_info=\u201c{}\u201c custom_padding__hover=\u201c|||\u201c][et_pb_image src=\u201chttps:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Steileis-Dolomiten-Klettern.webp\u201c alt=\u201cEisklettern in Kolfuschg im gadertal mit Bergf\u00fchrer\u201c title_text=\u201cSteileis Dolomiten Klettern\u201c show_in_lightbox=\u201con\u201c force_fullwidth=\u201con\u201c align_tablet=\u201ccenter\u201c align_phone=\u201ccenter\u201c align_last_edited=\u201con|desktop\u201c _builder_version=\u201c4.27.5\u2033 animation_style=\u201czoom\u201c animation_direction=\u201cleft\u201c animation_duration=\u201c500ms\u201c animation_delay=\u201c200ms\u201c animation_intensity_zoom=\u201c10%\u201c locked=\u201coff\u201c global_colors_info=\u201c{}\u201c][\/et_pb_image][\/et_pb_column][et_pb_column type=\u201c1_4\u2033 _builder_version=\u201c4.16\u2033 custom_padding=\u201c|||\u201c global_colors_info=\u201c{}\u201c custom_padding__hover=\u201c|||\u201c][et_pb_image src=\u201chttps:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Klettersteig-Rosengarten-Bergfuehrer-Dolomiten.webp\u201c alt=\u201cKlettersteig Dolomiten Rosengarten Molignon Seiser Alm\u201c title_text=\u201cKlettersteig Rosengarten Bergf\u00fchrer Dolomiten\u201c show_in_lightbox=\u201con\u201c force_fullwidth=\u201con\u201c align_tablet=\u201ccenter\u201c align_phone=\u201ccenter\u201c align_last_edited=\u201con|desktop\u201c _builder_version=\u201c4.27.5\u2033 animation_style=\u201czoom\u201c animation_duration=\u201c500ms\u201c animation_delay=\u201c300ms\u201c animation_intensity_zoom=\u201c10%\u201c locked=\u201coff\u201c global_colors_info=\u201c{}\u201c][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_column type=\u201c4_4\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_text _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c]<h3 style=\"text-align: center;\">VIVERE LA MONTAGNA CON LA VOSTRA GUIDA ALPINA:<\/h3>\n<h3 style=\"text-align: center;\">ARRAMPICATE E SALITE NELLE DOLOMITI, IN SUDTIROLO, NELLE ALPI E IN TUTTO IL MONDO<\/h3>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u201c1_3,1_3,1_3\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c custom_css_main_element=\u201cdisplay: flex;\u201c global_colors_info=\u201c{}\u201c][et_pb_column type=\u201c1_3\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_post_slider include_categories=\u201c4\u2033 orderby=\u201crand\u201c more_text=\u201cMehr\u201c use_manual_excerpt=\u201coff\u201c excerpt_length=\u201c0\u2033 show_meta=\u201coff\u201c _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c border_radii=\u201con|16px|16px|16px|16px\u201c box_shadow_style=\u201cpreset1\u2033 global_colors_info=\u201c{}\u201c more_text__hover_enabled=\u201coff|desktop\u201c][\/et_pb_post_slider][\/et_pb_column][et_pb_column type=\u201c1_3\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_post_slider include_categories=\u201c12\u2033 more_text=\u201cMehr\u201c excerpt_length=\u201c0\u2033 show_meta=\u201coff\u201c _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c border_radii=\u201con|16px|16px|16px|16px\u201c box_shadow_style=\u201cpreset1\u2033 global_colors_info=\u201c{}\u201c][\/et_pb_post_slider][\/et_pb_column][et_pb_column type=\u201c1_3\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_post_slider include_categories=\u201c4\u2033 orderby=\u201crand\u201c more_text=\u201cMehr\u201c excerpt_length=\u201c0\u2033 show_meta=\u201coff\u201c _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c border_radii=\u201con|16px|16px|16px|16px\u201c box_shadow_style=\u201cpreset1\u2033 global_colors_info=\u201c{}\u201c][\/et_pb_post_slider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_column type=\u201c4_4\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_text _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c]<h4 style=\"text-align: center;\">Vi accompagno come guida alpina nelle vostre salite: estate e inverno. Nelle Dolomiti, le mie montagne di casa, nelle Alpi occidentali e ovunque ci siano montagne.<\/h4>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c custom_padding=\u201c14px|||||\u201c global_colors_info=\u201c{}\u201c][et_pb_column type=\u201c4_4\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_text _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c link_option_url=\u201cthomasgianola.com\/klettern-dolomiten\/\u201c global_colors_info=\u201c{}\u201c]<h5 style=\"text-align: center;\">DOLOMITI<\/h5>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_column type=\u201c4_4\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_text _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c custom_padding=\u201c||1px|||\u201c global_colors_info=\u201c{}\u201c]<p style=\"text-align: center;\">Per gli arrampicatori e gli alpinisti, le Dolomiti sono uno dei pi\u00f9 grandi parchi giochi delle Alpi e del mondo. Come guida alpina e scalatore, \u00e8 qui che trascorro la maggior parte del mio tempo sul mio elemento preferito, la roccia. Essere accompagnati da una guida alpina locale non solo garantisce un'escursione sicura, ma anche la migliore scelta possibile del percorso.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c]<h5 style=\"text-align: center;\">CIME E VIE NORMALI IN DOLOMITI<\/h5>[\/et_pb_text][et_pb_text _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c custom_padding=\u201c||1px|||\u201c global_colors_info=\u201c{}\u201c]<p style=\"text-align: center;\">Marmolada, Cima Grande o Cervino: come guida alpina, vi accompagner\u00f2 fino alla vetta dei vostri sogni. Oltre alle cime pi\u00f9 conosciute, ci sono molte grandi vette meno conosciute e per questo ancora pi\u00f9 belle nelle Dolomiti e nelle Alpi. Sar\u00f2 felice di aiutarvi a trovare la montagna giusta per voi. Per ogni persona che accompagno c'\u00e8 una salita adatta e speciale.\u00a0<\/p>[\/et_pb_text][et_pb_text _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c link_option_url=\u201cskitouren-dolomiten.com\u201c link_option_url_new_window=\u201con\u201c global_colors_info=\u201c{}\u201c]<h5 style=\"text-align: center;\">SCIALPINISMO<\/h5>[\/et_pb_text][et_pb_text _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c custom_padding=\u201c||1px|||\u201c global_colors_info=\u201c{}\u201c]<p style=\"text-align: center;\">Escursioni di Scialpinismo in Alto Adige, nelle Dolomiti, in Piemonte o in Norvegia. La compagnia di un professionista garantisce una buona scelta della gita e, idealmente, la migliore neve.<\/p>[\/et_pb_text][et_pb_text _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c link_option_url=\u201cskitouren-dolomiten.com\u201c link_option_url_new_window=\u201con\u201c global_colors_info=\u201c{}\u201c]<h5 style=\"text-align: center;\">VIAGGIARE<\/h5>[\/et_pb_text][et_pb_text _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c]<p>Viaggiare con la guida in Sardegna, Marocco o Giordania? La mia grande passione per i viaggi mi ha portato in ogni angolo del mondo e vorrei condividere le mie conoscenze con voi: Da un lato nella scelta della migliore destinazione, dall'altro nella migliore esperienza possibile grazie alla conoscenza del rispettivo paese e dell'area di arrampicata.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c background_image=\u201chttp:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Thomas-Gianola-Dolomiten-Bergfuehrer-Gipfel.webp\u201c global_colors_info=\u201c{}\u201c][et_pb_column type=\u201c4_4\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_button button_url=\u201chttp:\/\/thomasgianola.com\/thomas-gianola-bergfuehrer\u201c button_text=\u201c\u00dcBER MICH\u201c button_alignment=\u201ccenter\u201c _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c custom_button=\u201con\u201c button_text_color=\u201c#FFFFFF\u201c button_border_width=\u201c5px\u201c button_border_radius=\u201c16px\u201c global_colors_info=\u201c{}\u201c][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u201c1_4,1_4,1_4,1_4\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_column type=\u201c1_4\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_image src=\u201chttp:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Schleierkante-Cima-della-Madonna.jpg\u201c alt=\u201cSchleierkante Spigolo del Velo Dolomiten Klettern\u201c title_text=\u201cSchleierkante Cima della Madonna\u201c _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][\/et_pb_image][\/et_pb_column][et_pb_column type=\u201c1_4\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_image src=\u201chttp:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Klettersteig-Gardasee-Cima-Capi.webp\u201c alt=\u201cKlettersteig am Gardasee Cima Capi mit Bergf\u00fchrer\u201c title_text=\u201cKlettersteig Gardasee Cima Capi\u201c _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][\/et_pb_image][\/et_pb_column][et_pb_column type=\u201c1_4\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_image src=\u201chttp:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Skitour-Norwegen-Thomas-Gianola.webp\u201c alt=\u201cSkitour Norwegen Thomas Gianola bergf\u00fchrer\u201c title_text=\u201cSkitour Norwegen Thomas Gianola\u201c _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][\/et_pb_image][\/et_pb_column][et_pb_column type=\u201c1_4\u2033 _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c global_colors_info=\u201c{}\u201c][et_pb_image src=\u201chttp:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Civetta-Pan-di-Zucchero-Klettern.jpg\u201c alt=\u201cKlettern am Pan di Zucchero Civetta\u201c title_text=\u201cCivetta Pan di Zucchero Klettern\u201c _builder_version=\u201c4.27.5\u2033 _module_preset=\u201cdefault\u201c width=\u201c100%\u201c global_colors_info=\u201c{}\u201c][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u201c1_3,1_3,1_3\u2033 admin_label=\u201cRow\u201c _builder_version=\u201c4.27.5\u2033 background_image=\u201chttps:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/dolomiten-sonnenuntergang-bergfuhrer.webp\u201c custom_padding=\u201c70px|||\u201c locked=\u201coff\u201c global_colors_info=\u201c{}\u201c][et_pb_column type=\u201c1_3\u2033 _builder_version=\u201c4.16\u2033 custom_padding=\u201c|||\u201c global_colors_info=\u201c{}\u201c custom_padding__hover=\u201c|||\u201c][et_pb_blurb title=\u201cwhatsapp\u201c url=\u201chttp:\/\/wa.me\/+393469451643\u2033 use_icon=\u201con\u201c font_icon=\u201c\uf39f||fa||400\u2033 icon_color=\u201c#ed4441\u2033 image_icon_background_color=\u201crgba(255,255,255,0)\u201c image_icon_width=\u201c36px\u201c _builder_version=\u201c4.27.5\u2033 header_font=\u201cOswald|on||on|\u201c header_text_color=\u201c#1a1a1a\u201c header_font_size=\u201c24px\u201c header_line_height=\u201c1.9em\u201c body_font=\u201cRoboto||||\u201c body_font_size=\u201c16px\u201c body_line_height=\u201c1.8em\u201c background_color=\u201c#f4f4f4\u2033 background_size=\u201cinitial\u201c background_position=\u201ctop_left\u201c background_repeat=\u201crepeat\u201c image_icon_custom_padding=\u201c25px|25px|25px|25px|false|false\u201c text_orientation=\u201ccenter\u201c custom_padding=\u201c60px||60px|\u201c link_option_url=\u201cwa.me\/+393469451643\u2033 border_radii_image=\u201con|100%|100%|100%|100%\u201c border_width_all_image=\u201c3px\u201c border_color_all_image=\u201c#ed4441\u2033 icon_font_size=\u201c36px\u201c use_circle=\u201con\u201c use_circle_border=\u201con\u201c circle_border_color=\u201c#ed4441\u2033 circle_color=\u201crgba(255,255,255,0)\u201c global_colors_info=\u201c{}\u201c image_icon_background_color__sticky_enabled=\u201c#7EBEC5\u2033 image_icon_background_color__sticky=\u201c#7EBEC5\u2033]<p><a href=\"https:\/\/Wa.me\/+393469451643\">\u00a0+39 3469451643<\/a><\/p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u201c1_3\u2033 _builder_version=\u201c4.16\u2033 custom_padding=\u201c|||\u201c global_colors_info=\u201c{}\u201c custom_padding__hover=\u201c|||\u201c][et_pb_blurb title=\u201ctelefon\u201c url=\u201ctel:00393469451643\u2033 url_new_window=\u201con\u201c use_icon=\u201con\u201c font_icon=\u201c\ue090||divi||400\u2033 icon_color=\u201c#ed4441\u2033 image_icon_background_color=\u201crgba(255,255,255,0)\u201c image_icon_width=\u201c36px\u201c _builder_version=\u201c4.27.5\u2033 header_font=\u201cOswald|on||on|\u201c header_text_color=\u201c#1a1a1a\u201c header_font_size=\u201c24px\u201c header_line_height=\u201c1.9em\u201c body_font=\u201cRoboto||||\u201c body_font_size=\u201c16px\u201c body_line_height=\u201c1.8em\u201c background_color=\u201c#f4f4f4\u2033 background_size=\u201cinitial\u201c background_position=\u201ctop_left\u201c background_repeat=\u201crepeat\u201c image_icon_custom_padding=\u201c25px|25px|25px|25px|false|false\u201c text_orientation=\u201ccenter\u201c custom_padding=\u201c60px||60px|\u201c link_option_url=\u201ctel:00393469451643\u2033 link_option_url_new_window=\u201con\u201c border_radii_image=\u201con|100%|100%|100%|100%\u201c border_width_all_image=\u201c3px\u201c border_color_all_image=\u201c#ed4441\u2033 icon_font_size=\u201c36px\u201c use_circle=\u201con\u201c use_circle_border=\u201con\u201c circle_border_color=\u201c#ed4441\u2033 circle_color=\u201crgba(255,255,255,0)\u201c global_colors_info=\u201c{}\u201c image_icon_background_color__sticky_enabled=\u201c#7EBEC5\u2033 image_icon_background_color__sticky=\u201c#7EBEC5\u2033]<p><a href=\"tel:00393469451643\">\u00a0+39 3469451643<\/a><\/p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u201c1_3\u2033 _builder_version=\u201c4.16\u2033 custom_padding=\u201c|||\u201c global_colors_info=\u201c{}\u201c custom_padding__hover=\u201c|||\u201c][et_pb_blurb title=\u201cEMail \u201c use_icon=\u201con\u201c font_icon=\u201c\ue080||divi||400\u2033 icon_color=\u201c#ed4441\u2033 image_icon_background_color=\u201crgba(255,255,255,0)\u201c image_icon_width=\u201c36px\u201c _builder_version=\u201c4.27.5\u2033 header_font=\u201cOswald|on||on|\u201c header_text_color=\u201c#1a1a1a\u201c header_font_size=\u201c24px\u201c header_line_height=\u201c1.9em\u201c body_font=\u201cRoboto||||\u201c body_font_size=\u201c16px\u201c body_line_height=\u201c1.8em\u201c background_color=\u201c#f4f4f4\u2033 background_size=\u201cinitial\u201c background_position=\u201ctop_left\u201c background_repeat=\u201crepeat\u201c image_icon_custom_padding=\u201c25px|25px|25px|25px|false|false\u201c text_orientation=\u201ccenter\u201c custom_padding=\u201c60px||60px|\u201c animation_style=\u201cfold\u201c animation_direction=\u201cleft\u201c animation_intensity_fold=\u201c41%\u201c border_radii_image=\u201con|100%|100%|100%|100%\u201c border_width_all_image=\u201c3px\u201c border_color_all_image=\u201c#ed4441\u2033 icon_font_size=\u201c36px\u201c use_circle=\u201con\u201c use_circle_border=\u201con\u201c circle_border_color=\u201c#ed4441\u2033 circle_color=\u201crgba(255,255,255,0)\u201c global_colors_info=\u201c{}\u201c image_icon_background_color__sticky_enabled=\u201c#7EBEC5\u2033 image_icon_background_color__sticky=\u201c#7EBEC5\u2033]<p><a href=\"mailto:thomas.gianola@hotmail.it\">thomas.gianola@hotmail.it<\/a><\/p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>VIVI LE MONTAGNE CON LA TUA GUIDA ALPINA: ESCURSIONI PROFESSIONALI NELLE DOLOMITI, ALTO ADIGE, ALPI E IN TUTTO IL MONDO Ti accompagno come guida alpina durante le escursioni: estate e inverno. Nelle Dolomiti, le mie montagne di casa, cos\u00ec come nelle Alpi Occidentali e ovunque ci siano montagne. DOLOMITI Le Dolomiti sono, per rocciatori e alpinisti, uno dei pi\u00f9 grandi parchi giochi delle Alpi e [...]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-250","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bergf\u00fchrer Dolomiten - Thomas Gianola Bergf\u00fchrer Dolomiten<\/title>\n<meta name=\"description\" content=\"Gef\u00fchrte Klettertouren, Klettersteige,Ski- und Hochtouren in den Dolomiten und in S\u00fcdtirol mit Bergf\u00fchrer Thomas Gianola\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thomasgianola.com\/it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bergf\u00fchrer Dolomiten - Thomas Gianola Bergf\u00fchrer Dolomiten\" \/>\n<meta property=\"og:description\" content=\"Gef\u00fchrte Klettertouren, Klettersteige,Ski- und Hochtouren in den Dolomiten und in S\u00fcdtirol mit Bergf\u00fchrer Thomas Gianola\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thomasgianola.com\/it\/\" \/>\n<meta property=\"og:site_name\" content=\"Thomas Gianola Bergf\u00fchrer Dolomiten\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tgianola.mountainguide\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-18T16:24:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/\",\"url\":\"https:\\\/\\\/thomasgianola.com\\\/\",\"name\":\"Bergf\u00fchrer Dolomiten - Thomas Gianola Bergf\u00fchrer Dolomiten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#website\"},\"datePublished\":\"2026-01-15T16:46:47+00:00\",\"dateModified\":\"2026-02-18T16:24:53+00:00\",\"description\":\"Gef\u00fchrte Klettertouren, Klettersteige,Ski- und Hochtouren in den Dolomiten und in S\u00fcdtirol mit Bergf\u00fchrer Thomas Gianola\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thomasgianola.com\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thomasgianola.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bergf\u00fchrer Dolomiten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#website\",\"url\":\"https:\\\/\\\/thomasgianola.com\\\/\",\"name\":\"Thomas Gianola Bergf\u00fchrer - mountainguide\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#\\\/schema\\\/person\\\/1eca9a4b029a522ad9c12bca4d072b52\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thomasgianola.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#\\\/schema\\\/person\\\/1eca9a4b029a522ad9c12bca4d072b52\",\"name\":\"Thomas.gianola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp\",\"url\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp\",\"contentUrl\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp\",\"width\":2016,\"height\":1134,\"caption\":\"Thomas.gianola\"},\"logo\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp\"},\"sameAs\":[\"https:\\\/\\\/thomasgianola.com\",\"https:\\\/\\\/www.facebook.com\\\/tgianola.mountainguide\",\"https:\\\/\\\/www.instagram.com\\\/thomas.gianola\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guida alpina Dolomiti - Thomas Gianola Guida alpina Dolomiti","description":"Vie lunghe e arrampicata inmontagna, vie ferrate, escursioni di scialpinismo e alpinismo classico nelle Dolomiti e in Alto Adige con la guida alpina Thomas Gianola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thomasgianola.com\/it\/","og_locale":"it_IT","og_type":"article","og_title":"Bergf\u00fchrer Dolomiten - Thomas Gianola Bergf\u00fchrer Dolomiten","og_description":"Gef\u00fchrte Klettertouren, Klettersteige,Ski- und Hochtouren in den Dolomiten und in S\u00fcdtirol mit Bergf\u00fchrer Thomas Gianola","og_url":"https:\/\/thomasgianola.com\/it\/","og_site_name":"Thomas Gianola Bergf\u00fchrer Dolomiten","article_publisher":"https:\/\/www.facebook.com\/tgianola.mountainguide","article_modified_time":"2026-02-18T16:24:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thomasgianola.com\/","url":"https:\/\/thomasgianola.com\/","name":"Guida alpina Dolomiti - Thomas Gianola Guida alpina Dolomiti","isPartOf":{"@id":"https:\/\/thomasgianola.com\/#website"},"datePublished":"2026-01-15T16:46:47+00:00","dateModified":"2026-02-18T16:24:53+00:00","description":"Vie lunghe e arrampicata inmontagna, vie ferrate, escursioni di scialpinismo e alpinismo classico nelle Dolomiti e in Alto Adige con la guida alpina Thomas Gianola","breadcrumb":{"@id":"https:\/\/thomasgianola.com\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thomasgianola.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thomasgianola.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thomasgianola.com\/"},{"@type":"ListItem","position":2,"name":"Bergf\u00fchrer Dolomiten"}]},{"@type":"WebSite","@id":"https:\/\/thomasgianola.com\/#website","url":"https:\/\/thomasgianola.com\/","name":"Thomas Gianola Guida alpina - mountainguide","description":"","publisher":{"@id":"https:\/\/thomasgianola.com\/#\/schema\/person\/1eca9a4b029a522ad9c12bca4d072b52"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thomasgianola.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/thomasgianola.com\/#\/schema\/person\/1eca9a4b029a522ad9c12bca4d072b52","name":"Tommaso.gianola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/02\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp","url":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/02\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp","contentUrl":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/02\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp","width":2016,"height":1134,"caption":"Thomas.gianola"},"logo":{"@id":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/02\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp"},"sameAs":["https:\/\/thomasgianola.com","https:\/\/www.facebook.com\/tgianola.mountainguide","https:\/\/www.instagram.com\/thomas.gianola\/"]}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/pages\/250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/comments?post=250"}],"version-history":[{"count":33,"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/pages\/250\/revisions"}],"predecessor-version":[{"id":1373,"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/pages\/250\/revisions\/1373"}],"wp:attachment":[{"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/media?parent=250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}