{"id":470,"date":"2026-01-26T18:06:13","date_gmt":"2026-01-26T18:06:13","guid":{"rendered":"https:\/\/thomasgianola.com\/?p=470"},"modified":"2026-02-12T20:07:03","modified_gmt":"2026-02-12T20:07:03","slug":"tre-cime","status":"publish","type":"post","link":"https:\/\/thomasgianola.com\/it\/tre-cime\/","title":{"rendered":"Tre Cime di Lavaredo"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; admin_label=&#8220;Hero&#8220; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#233b4e&#8220; parallax=&#8220;on&#8220; custom_padding=&#8220;0px|0px|0px|0px&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_fullwidth_header title=&#8220;Drei zinnen&#8220; subhead=&#8220;Gef\u00fchrte Touren auf die Gipfel der Drei Zinnen&#8220; button_one_text=&#8220;Anfrage Senden&#8220; button_one_url=&#8220;thomasgianola.com\/kontakt&#8220; background_overlay_color=&#8220;rgba(29,38,51,0.86)&#8220; content_max_width=&#8220;700px&#8220; admin_label=&#8220;Hero Section&#8220; _builder_version=&#8220;4.27.5&#8243; title_font=&#8220;Oswald|on||on|&#8220; title_font_size=&#8220;42px&#8220; title_line_height=&#8220;1.3em&#8220; content_font=&#8220;Roboto||||&#8220; content_font_size=&#8220;20px&#8220; background_color=&#8220;rgba(255, 255, 255, 0)&#8220; background_image=&#8220;https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Drei-Zinnen-Blick-Bergfuehrer.webp&#8220; parallax=&#8220;on&#8220; parallax_method=&#8220;on&#8220; custom_button_one=&#8220;on&#8220; button_one_border_radius=&#8220;0px&#8220; button_one_letter_spacing=&#8220;4px&#8220; button_one_font=&#8220;Oswald|on||on|&#8220; button_one_icon=&#8220;&#x24;||divi||400&#8243; button_one_icon_color=&#8220;#ffffff&#8220; custom_margin=&#8220;|||&#8220; custom_padding=&#8220;150px||150px|&#8220; custom_padding_tablet=&#8220;60px||60px|&#8220; custom_padding_phone=&#8220;&#8220; custom_padding_last_edited=&#8220;on|tablet&#8220; animation_style=&#8220;zoom&#8220; animation_direction=&#8220;bottom&#8220; animation_intensity_zoom=&#8220;4%&#8220; hover_enabled=&#8220;0&#8243; button_one_text_color_hover=&#8220;#ffffff&#8220; button_one_border_color_hover=&#8220;#ffffff&#8220; button_one_border_radius_hover=&#8220;0px&#8220; button_one_letter_spacing_hover=&#8220;4px&#8220; button_one_bg_color_hover=&#8220;rgba(0,0,0,0)&#8220; global_colors_info=&#8220;{}&#8220; button_one_text_size__hover_enabled=&#8220;off&#8220; button_two_text_size__hover_enabled=&#8220;off&#8220; button_one_text_color__hover_enabled=&#8220;on&#8220; button_one_text_color__hover=&#8220;#ffffff&#8220; button_two_text_color__hover_enabled=&#8220;off&#8220; button_one_border_width__hover_enabled=&#8220;off&#8220; button_two_border_width__hover_enabled=&#8220;off&#8220; button_one_border_color__hover_enabled=&#8220;on&#8220; button_one_border_color__hover=&#8220;#ffffff&#8220; button_two_border_color__hover_enabled=&#8220;off&#8220; button_one_border_radius__hover_enabled=&#8220;on&#8220; button_one_border_radius__hover=&#8220;0px&#8220; button_two_border_radius__hover_enabled=&#8220;off&#8220; button_one_letter_spacing__hover_enabled=&#8220;on&#8220; button_one_letter_spacing__hover=&#8220;4px&#8220; button_two_letter_spacing__hover_enabled=&#8220;off&#8220; button_one_bg_color__hover_enabled=&#8220;on&#8220; button_one_bg_color__hover=&#8220;rgba(0,0,0,0)&#8220; button_two_bg_color__hover_enabled=&#8220;off&#8220; button_one_text__hover_enabled=&#8220;off|desktop&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Gallery&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;0px||0px|&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; make_equal=&#8220;on&#8220; module_class=&#8220; four-columns&#8220; _builder_version=&#8220;4.27.5&#8243; width=&#8220;100%&#8220; width_tablet=&#8220;100%&#8220; width_phone=&#8220;100%&#8220; width_last_edited=&#8220;on|desktop&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; max_width_last_edited=&#8220;on|desktop&#8220; custom_padding=&#8220;0px|0px|0px|0px||&#8220; make_fullwidth=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Klettern-grosse-Zinne-Bergfuehrer.webp&#8220; alt=&#8220;Fels und Nebel am Zinnen Normalweg mit Guide&#8220; title_text=&#8220;Klettern gro\u00dfe Zinne Bergf\u00fchrer&#8220; show_in_lightbox=&#8220;on&#8220; force_fullwidth=&#8220;on&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.27.5&#8243; custom_padding=&#8220;||0px|||&#8220; animation_style=&#8220;zoom&#8220; animation_direction=&#8220;left&#8220; animation_duration=&#8220;500ms&#8220; animation_intensity_zoom=&#8220;10%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Thomas-Gianola-Drei-Zinnen-guide.jpg&#8220; alt=&#8220;Bergf\u00fchrer Guide Thomas Gianola in den Dolomiten beim f\u00fchren auf die Gro\u00dfe Zinne&#8220; title_text=&#8220;Thomas Gianola Drei Zinnen guide&#8220; show_in_lightbox=&#8220;on&#8220; force_fullwidth=&#8220;on&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.27.5&#8243; animation_style=&#8220;zoom&#8220; animation_direction=&#8220;left&#8220; animation_duration=&#8220;500ms&#8220; animation_delay=&#8220;100ms&#8220; animation_intensity_zoom=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Klettern-Westliche-Zinne-drei-Zinnen.webp&#8220; alt=&#8220;Klettern auf die Westliche Zinne mit Bergf\u00fchrer&#8220; title_text=&#8220;Klettern Westliche Zinne drei Zinnen&#8220; show_in_lightbox=&#8220;on&#8220; force_fullwidth=&#8220;on&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.27.5&#8243; animation_style=&#8220;zoom&#8220; animation_direction=&#8220;left&#8220; animation_duration=&#8220;500ms&#8220; animation_delay=&#8220;200ms&#8220; animation_intensity_zoom=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Klettern-Normalweg-Grosse-Zinne.webp&#8220; alt=&#8220;Klettern auf die Gro\u00dfe Zinne&#8220; title_text=&#8220;Klettern Normalweg Gro\u00dfe Zinne&#8220; show_in_lightbox=&#8220;on&#8220; force_fullwidth=&#8220;on&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.27.5&#8243; custom_margin=&#8220;||-143px|||&#8220; animation_style=&#8220;zoom&#8220; animation_duration=&#8220;500ms&#8220; animation_delay=&#8220;300ms&#8220; animation_intensity_zoom=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; min_height=&#8220;1258.7px&#8220; custom_margin=&#8220;||-175px|||&#8220; custom_padding=&#8220;8px||0px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Discover Beatuty Title&#8220; _builder_version=&#8220;4.27.5&#8243; text_font=&#8220;||||&#8220; text_text_color=&#8220;#1a1a1a&#8220; header_font=&#8220;Oswald|on||on|&#8220; header_text_align=&#8220;left&#8220; header_font_size=&#8220;60px&#8220; header_line_height=&#8220;1.3em&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;%22fade_in%22&#8243; animation_duration=&#8220;500ms&#8220; animation_intensity_slide=&#8220;10%&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Cima Grande, Cima Occidentale e Cima Piccola con guida alpina<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8220;Discover Beatuty Sub Title&#8220; _builder_version=&#8220;4.27.5&#8243; text_font=&#8220;Roboto||||&#8220; text_text_color=&#8220;#1a1a1a&#8220; text_font_size=&#8220;24px&#8220; text_line_height=&#8220;1.4em&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_delay=&#8220;100ms&#8220; animation_intensity_slide=&#8220;10%&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4>Cime iconiche delle Dolomiti<\/h4>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;#ed4441&#8243; divider_position=&#8220;center&#8220; divider_weight=&#8220;3px&#8220; disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.16&#8243; max_width=&#8220;150px&#8220; height=&#8220;false&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_delay=&#8220;200ms&#8220; animation_intensity_slide=&#8220;10%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][et_pb_text disabled_on=&#8220;on|on|off%22%22&#8243; admin_label=&#8220;Discover Beatuty Text&#8220; _builder_version=&#8220;4.27.5&#8243; text_font=&#8220;Roboto||||&#8220; text_font_size=&#8220;16px&#8220; text_line_height=&#8220;1.9em&#8220; custom_padding=&#8220;30px|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_delay=&#8220;300ms&#8220; animation_intensity_slide=&#8220;10%&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p data-start=\"162\" data-end=\"562\">Le Tre Cime sono probabilmente le montagne pi\u00f9 fotografate delle Dolomiti e anche le pi\u00f9 famose. La tipica immagine delle Tre Cime le ritrae dal versante nord. Sulle pareti settentrionali si possono fare delle bellissime arrampicate, come ad esempio la <a href=\"\/it\/thomasgianola.com\/dolomiti-vie-classiche\/\">Comici<\/a> alla Cima Grande o la via Cassin alla Cima Ovest.<\/p>\n<p data-start=\"162\" data-end=\"562\">Sul versante sud invece le cime sono decisamente pi\u00f9 facili da raggiungere con una guida alpina. Ci\u00f2 non significa che le vie normali debbano essere sottovalutate: Con un buon livello di allenamento, passo sicuro e capacit\u00e0 di arrampicare sul terzo grado, qualsiasi alpinista pu\u00f2 raggiungere le cime della Cima Grande e della Cima Ovest di Lavaredo. La via normale alla Cima Piccola, invece, \u00e8 pi\u00f9 simile a un via di arrampicata vera e propria: qui si scala sul terzo e quarto grado.<\/p>\n<p data-start=\"162\" data-end=\"562\">\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Drei-Zinnen-Blick-Bergfuehrer.webp&#8220; alt=&#8220;Drei Zinnen Nordw\u00e4nde Klettern ausblick&#8220; title_text=&#8220;Drei Zinnen Blick Bergf\u00fchrer&#8220; force_fullwidth=&#8220;on&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.27.5&#8243; custom_margin=&#8220;90px|||&#8220; animation_style=&#8220;fold&#8220; animation_direction=&#8220;right&#8220; animation_intensity_fold=&#8220;20%&#8220; border_radii=&#8220;on|16px|16px|16px|16px&#8220; box_shadow_style=&#8220;preset2&#8243; animation=&#8220;fade_in&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; min_height=&#8220;2426.4px&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.16&#8243; min_height=&#8220;446.7px&#8220; custom_margin=&#8220;-432px|auto||auto||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Title&#8220; _builder_version=&#8220;4.27.5&#8243; text_font=&#8220;||||&#8220; text_text_color=&#8220;#1a1a1a&#8220; header_font=&#8220;Oswald|on||on|&#8220; header_text_align=&#8220;left&#8220; header_font_size=&#8220;60px&#8220; header_line_height=&#8220;1.3em&#8220; max_width=&#8220;450px&#8220; custom_margin=&#8220;|||&#8220; custom_padding=&#8220;|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_intensity_slide=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Cima Grande di Lavaredo<\/h3>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;#ed4441&#8243; divider_position=&#8220;center&#8220; divider_weight=&#8220;3px&#8220; disabled_on=&#8220;on|on|off%22&#8243; _builder_version=&#8220;4.16&#8243; max_width=&#8220;150px&#8220; height=&#8220;false&#8220; custom_margin=&#8220;30px|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_delay=&#8220;100ms&#8220; animation_intensity_slide=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][et_pb_text admin_label=&#8220;Sub Title&#8220; _builder_version=&#8220;4.27.5&#8243; text_font=&#8220;Roboto||||&#8220; text_text_color=&#8220;#1a1a1a&#8220; text_font_size=&#8220;24px&#8220; text_line_height=&#8220;1.4em&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; max_width=&#8220;450px&#8220; custom_padding=&#8220;30px|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_delay=&#8220;200ms&#8220; animation_intensity_slide=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>La Cima Grande \u00e8 probabilmente la cima pi\u00f9 popolare delle Tre Cime. La <a href=\"\/it\/thomasgianola.com\/dolomite-normalwege\/\">via normale<\/a> richiede esperienza per trovare la via e non perdersi. Passo sicuro per non inciampare sui vari passaggi facili ma esposti. Con una guida alpina siete in mani sicure.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Drei-Zinnen-Gipfel-mit-Bergfuehrer.jpg&#8220; alt=&#8220;Gipfel der Gro\u00dfen Zinne gef\u00fchrt mit Bergf\u00fchrer&#8220; title_text=&#8220;Drei Zinnen Gipfel mit Bergf\u00fchrer&#8220; force_fullwidth=&#8220;on&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.27.5&#8243; custom_margin=&#8220;|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;%22fade_in%22&#8243; animation_duration=&#8220;500ms&#8220; animation_intensity_slide=&#8220;10%&#8220; border_radii=&#8220;on|16px|16px|16px|16px&#8220; box_shadow_style=&#8220;preset1&#8243; animation=&#8220;fade_in&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_number_counter title=&#8220;max. Teilnehmer&#8220; number=&#8220;2&#8243; percent_sign=&#8220;off&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; number_text_color=&#8220;#963900&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>&nbsp;<\/p>\n<table border=\"1\" style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><strong>difficolt\u00e0 complessiva<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>3\/5 (750 hm)<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Difficolt\u00e0 tecniche<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>III+ (per lo pi\u00f9 II e pi\u00f9 facile)<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Prezzo (1 partecipante)<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>580 \u20ac<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Prezzo (2 partecipanti)<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>350 \u20ac<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><\/td>\n<td style=\"width: 50%;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Title&#8220; _builder_version=&#8220;4.27.5&#8243; text_font=&#8220;||||&#8220; text_text_color=&#8220;#1a1a1a&#8220; header_font=&#8220;Oswald|on||on|&#8220; header_text_align=&#8220;left&#8220; header_font_size=&#8220;60px&#8220; header_line_height=&#8220;1.3em&#8220; max_width=&#8220;450px&#8220; custom_margin=&#8220;|||&#8220; custom_padding=&#8220;|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_intensity_slide=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Cima Ovest di Lavaredo<\/h3>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;#ed4441&#8243; divider_position=&#8220;center&#8220; divider_weight=&#8220;3px&#8220; disabled_on=&#8220;on|on|off%22&#8243; _builder_version=&#8220;4.16&#8243; max_width=&#8220;150px&#8220; height=&#8220;false&#8220; custom_margin=&#8220;30px|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_delay=&#8220;100ms&#8220; animation_intensity_slide=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][et_pb_text admin_label=&#8220;Sub Title&#8220; _builder_version=&#8220;4.27.5&#8243; text_font=&#8220;Roboto||||&#8220; text_text_color=&#8220;#1a1a1a&#8220; text_font_size=&#8220;24px&#8220; text_line_height=&#8220;1.4em&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; max_width=&#8220;450px&#8220; custom_padding=&#8220;30px|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_delay=&#8220;200ms&#8220; animation_intensity_slide=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>La Cima Ovest \u00e8 tecnicamente pi\u00f9 facile della Cima Grande e le difficolt\u00e0 sono meno continue. Meno frequentato della sua vicina pi\u00f9 grande, questo cima offre un'avventura indimenticabile con una guida alpina.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Klettern-Westliche-Zinne-drei-Zinnen.webp&#8220; alt=&#8220;Klettern auf die Westliche Zinne mit Bergf\u00fchrer&#8220; title_text=&#8220;Klettern Westliche Zinne drei Zinnen&#8220; force_fullwidth=&#8220;on&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.27.5&#8243; custom_margin=&#8220;|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;%22fade_in%22&#8243; animation_duration=&#8220;500ms&#8220; animation_intensity_slide=&#8220;10%&#8220; border_radii=&#8220;on|17px|17px|17px|17px&#8220; box_shadow_style=&#8220;preset2&#8243; animation=&#8220;fade_in&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_number_counter title=&#8220;max. Teilnehmer&#8220; number=&#8220;2&#8243; percent_sign=&#8220;off&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; number_text_color=&#8220;#963900&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<table border=\"1\" style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><strong>difficolt\u00e0 complessiva<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>3\/5\u00a0<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Difficolt\u00e0 tecniche<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>III (passaggi brevi)<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Prezzo (1 partecipante)<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>580 \u20ac<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Prezzo (2 partecipanti)<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>350 \u20ac<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><\/td>\n<td style=\"width: 50%;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Title&#8220; _builder_version=&#8220;4.27.5&#8243; text_font=&#8220;||||&#8220; text_text_color=&#8220;#1a1a1a&#8220; header_font=&#8220;Oswald|on||on|&#8220; header_text_align=&#8220;left&#8220; header_font_size=&#8220;60px&#8220; header_line_height=&#8220;1.3em&#8220; max_width=&#8220;450px&#8220; custom_margin=&#8220;|||&#8220; custom_padding=&#8220;|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_intensity_slide=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Via normale Cima piccola di Lavaredo<\/h3>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;#ed4441&#8243; divider_position=&#8220;center&#8220; divider_weight=&#8220;3px&#8220; disabled_on=&#8220;on|on|off%22&#8243; _builder_version=&#8220;4.16&#8243; max_width=&#8220;150px&#8220; height=&#8220;false&#8220; custom_margin=&#8220;30px|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_delay=&#8220;100ms&#8220; animation_intensity_slide=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][et_pb_text admin_label=&#8220;Sub Title&#8220; _builder_version=&#8220;4.27.5&#8243; text_font=&#8220;Roboto||||&#8220; text_text_color=&#8220;#1a1a1a&#8220; text_font_size=&#8220;24px&#8220; text_line_height=&#8220;1.4em&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; max_width=&#8220;450px&#8220; custom_padding=&#8220;30px|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; animation_delay=&#8220;200ms&#8220; animation_intensity_slide=&#8220;10%&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>La via normale alla Cima Piccola \u00e8 tecnicamente la pi\u00f9 difficile delle tre cime. Questa salita \u00e8 quasi pi\u00f9 simile a una classica via a pi\u00f9 tiri che a una via normale. Qui si scala anche sul quarto grado.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Aussicht-Drei-Zinnenhuette-Bergfuehrer.webp&#8220; alt=&#8220;Ausblick auf die Dreizinnenh\u00fctte und den Paternkofel auf Tour mit Bergf\u00fchrer&#8220; title_text=&#8220;Aussicht Drei Zinnenh\u00fctte Bergf\u00fchrer&#8220; force_fullwidth=&#8220;on&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.27.5&#8243; custom_margin=&#8220;|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;%22fade_in%22&#8243; animation_duration=&#8220;500ms&#8220; animation_intensity_slide=&#8220;10%&#8220; border_radii=&#8220;on|16px|16px|16px|16px&#8220; box_shadow_style=&#8220;preset1&#8243; animation=&#8220;fade_in&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_number_counter title=&#8220;max. Teilnehmer&#8220; number=&#8220;2&#8243; percent_sign=&#8220;off&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; number_text_color=&#8220;#963900&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>&nbsp;<\/p>\n<table border=\"1\" style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><strong>difficolt\u00e0 complessiva<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>3\/5\u00a0<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Difficolt\u00e0 tecniche<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>IV (UIAA)<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Prezzo (1 partecipante)<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>580 \u20ac<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Prezzo (2 partecipanti)<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>330 \u20ac<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><\/td>\n<td style=\"width: 50%;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_post_slider include_categories=&#8220;4&#8243; orderby=&#8220;rand&#8220; use_manual_excerpt=&#8220;off&#8220; excerpt_length=&#8220;0&#8243; show_meta=&#8220;off&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|12px|12px|12px|12px&#8220; box_shadow_style=&#8220;preset1&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_post_slider][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_post_slider include_categories=&#8220;12&#8243; excerpt_length=&#8220;0&#8243; show_meta=&#8220;off&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|12px|12px|12px|12px&#8220; box_shadow_style=&#8220;preset1&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_post_slider][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_post_slider include_categories=&#8220;4&#8243; orderby=&#8220;rand&#8220; excerpt_length=&#8220;0&#8243; show_meta=&#8220;off&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|12px|12px|12px|12px&#8220; box_shadow_style=&#8220;preset1&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_post_slider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; admin_label=&#8220;Row&#8220; _builder_version=&#8220;4.27.5&#8243; background_image=&#8220;https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/dolomiten-sonnenuntergang-bergfuhrer.webp&#8220; custom_padding=&#8220;70px|||&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_blurb title=&#8220;whatsapp&#8220; url=&#8220;http:\/\/wa.me\/+393469451643&#8243; use_icon=&#8220;on&#8220; font_icon=&#8220;&#xf39f;||fa||400&#8243; icon_color=&#8220;#ed4441&#8243; image_icon_background_color=&#8220;rgba(255,255,255,0)&#8220; image_icon_width=&#8220;36px&#8220; _builder_version=&#8220;4.27.5&#8243; header_font=&#8220;Oswald|on||on|&#8220; header_text_color=&#8220;#1a1a1a&#8220; header_font_size=&#8220;24px&#8220; header_line_height=&#8220;1.9em&#8220; body_font=&#8220;Roboto||||&#8220; body_font_size=&#8220;16px&#8220; body_line_height=&#8220;1.8em&#8220; background_color=&#8220;#f4f4f4&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; image_icon_custom_padding=&#8220;25px|25px|25px|25px|false|false&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;60px||60px|&#8220; link_option_url=&#8220;wa.me\/+393469451643&#8243; border_radii_image=&#8220;on|100%|100%|100%|100%&#8220; border_width_all_image=&#8220;3px&#8220; border_color_all_image=&#8220;#ed4441&#8243; icon_font_size=&#8220;36px&#8220; use_circle=&#8220;on&#8220; use_circle_border=&#8220;on&#8220; circle_border_color=&#8220;#ed4441&#8243; circle_color=&#8220;rgba(255,255,255,0)&#8220; global_colors_info=&#8220;{}&#8220; image_icon_background_color__sticky_enabled=&#8220;#7EBEC5&#8243; image_icon_background_color__sticky=&#8220;#7EBEC5&#8243;]<\/p>\n<p><a href=\"https:\/\/Wa.me\/+393469451643\">\u00a0+39 3469451643<\/a><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u201c1_3\u2033 _builder_version=\u201c4.16\u2033 custom_padding=\u201c|||\u201c global_colors_info=\u201c{}\u201c custom_padding__hover=\u201c|||\u201c][et_pb_blurb title=\u201ctelefon\u201c url=\u201ctel:00393469451643\u2033 url_new_window=\u201con\u201c use_icon=\u201con\u201c font_icon=\u201c\ue090||divi||400\u2033 icon_color=\u201c#ed4441\u2033 image_icon_background_color=\u201crgba(255,255,255,0)\u201c image_icon_width=\u201c36px\u201c _builder_version=\u201c4.27.5\u2033 header_font=\u201cOswald|on||on|\u201c header_text_color=\u201c#1a1a1a\u201c header_font_size=\u201c24px\u201c header_line_height=\u201c1.9em\u201c body_font=\u201cRoboto||||\u201c body_font_size=\u201c16px\u201c body_line_height=\u201c1.8em\u201c background_color=\u201c#f4f4f4\u2033 background_size=\u201cinitial\u201c background_position=\u201ctop_left\u201c background_repeat=\u201crepeat\u201c image_icon_custom_padding=\u201c25px|25px|25px|25px|false|false\u201c text_orientation=\u201ccenter\u201c custom_padding=\u201c60px||60px|\u201c link_option_url=\u201ctel:00393469451643\u2033 link_option_url_new_window=\u201con\u201c border_radii_image=\u201con|100%|100%|100%|100%\u201c border_width_all_image=\u201c3px\u201c border_color_all_image=\u201c#ed4441\u2033 icon_font_size=\u201c36px\u201c use_circle=\u201con\u201c use_circle_border=\u201con\u201c circle_border_color=\u201c#ed4441\u2033 circle_color=\u201crgba(255,255,255,0)\u201c global_colors_info=\u201c{}\u201c image_icon_background_color__sticky_enabled=\u201c#7EBEC5\u2033 image_icon_background_color__sticky=\u201c#7EBEC5\u2033]<\/p>\n<p><a href=\"tel:00393469451643\">\u00a0+39 3469451643<\/a><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u201c1_3\u2033 _builder_version=\u201c4.16\u2033 custom_padding=\u201c|||\u201c global_colors_info=\u201c{}\u201c custom_padding__hover=\u201c|||\u201c][et_pb_blurb title=\u201cEMail \u201c use_icon=\u201con\u201c font_icon=\u201c\ue080||divi||400\u2033 icon_color=\u201c#ed4441\u2033 image_icon_background_color=\u201crgba(255,255,255,0)\u201c image_icon_width=\u201c36px\u201c _builder_version=\u201c4.27.5\u2033 header_font=\u201cOswald|on||on|\u201c header_text_color=\u201c#1a1a1a\u201c header_font_size=\u201c24px\u201c header_line_height=\u201c1.9em\u201c body_font=\u201cRoboto||||\u201c body_font_size=\u201c16px\u201c body_line_height=\u201c1.8em\u201c background_color=\u201c#f4f4f4\u2033 background_size=\u201cinitial\u201c background_position=\u201ctop_left\u201c background_repeat=\u201crepeat\u201c image_icon_custom_padding=\u201c25px|25px|25px|25px|false|false\u201c text_orientation=\u201ccenter\u201c custom_padding=\u201c60px||60px|\u201c animation_style=\u201cfold\u201c animation_direction=\u201cleft\u201c animation_intensity_fold=\u201c41%\u201c border_radii_image=\u201con|100%|100%|100%|100%\u201c border_width_all_image=\u201c3px\u201c border_color_all_image=\u201c#ed4441\u2033 icon_font_size=\u201c36px\u201c use_circle=\u201con\u201c use_circle_border=\u201con\u201c circle_border_color=\u201c#ed4441\u2033 circle_color=\u201crgba(255,255,255,0)\u201c global_colors_info=\u201c{}\u201c image_icon_background_color__sticky_enabled=\u201c#7EBEC5\u2033 image_icon_background_color__sticky=\u201c#7EBEC5\u2033]<\/p>\n<p><a href=\"mailto:thomas.gianola@hotmail.it\">thomas.gianola@hotmail.it<\/a><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>Gro\u00dfe Zinne, Westliche und Kleine Zinne mit Bergf\u00fchrerIkonische Gipfel der DolomitenDie Drei Zinnen sind die wohl meist fotografierten Berge der Dolomiten und auch die bekanntesten. Das typische Bild der Drei Zinnen zeigt diese von ihrer Nordseite. Auf den Norw\u00e4nden gibt es einige gro\u00dfe Klettertouren wie die Comici an der Gro\u00dfen Zinne oder die Cassin-F\u00fchre an [&hellip;]<\/p>","protected":false},"author":1,"featured_media":541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1080","footnotes":""},"categories":[4],"tags":[8,6,25,7],"class_list":["post-470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dolomiten-normalwege","tag-bergfuhrer","tag-dolomiten","tag-drei-zinnen","tag-normalwege"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Drei Zinnen Normalwege mit Bergf\u00fchrer<\/title>\n<meta name=\"description\" content=\"Gef\u00fchrte Touren auf die Gipfel der Drei Zinnen. Gro\u00dfe Zinne Normalweg, Kleine Zinne und Westliche Zinne mit Bergf\u00fchrer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thomasgianola.com\/it\/tre-cime\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drei Zinnen Normalwege mit Bergf\u00fchrer\" \/>\n<meta property=\"og:description\" content=\"Gef\u00fchrte Touren auf die Gipfel der Drei Zinnen. Gro\u00dfe Zinne Normalweg, Kleine Zinne und Westliche Zinne mit Bergf\u00fchrer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thomasgianola.com\/it\/tre-cime\/\" \/>\n<meta property=\"og:site_name\" content=\"Thomas Gianola Bergf\u00fchrer Dolomiten\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tgianola.mountainguide\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/tgianola.mountainguide\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-26T18:06:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T20:07:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Drei-Zinnen-Blick-Bergfuehrer.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"4032\" \/>\n\t<meta property=\"og:image:height\" content=\"3024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Thomas.gianola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas.gianola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/\"},\"author\":{\"name\":\"Thomas.gianola\",\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#\\\/schema\\\/person\\\/1eca9a4b029a522ad9c12bca4d072b52\"},\"headline\":\"Drei Zinnen\",\"datePublished\":\"2026-01-26T18:06:13+00:00\",\"dateModified\":\"2026-02-12T20:07:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/\"},\"wordCount\":3270,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#\\\/schema\\\/person\\\/1eca9a4b029a522ad9c12bca4d072b52\"},\"image\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Drei-Zinnen-Blick-Bergfuehrer.webp\",\"keywords\":[\"bergf\u00fchrer\",\"dolomiten\",\"drei zinnen\",\"normalwege\"],\"articleSection\":[\"Dolomiten-Normalwege\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/\",\"url\":\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/\",\"name\":\"Drei Zinnen Normalwege mit Bergf\u00fchrer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Drei-Zinnen-Blick-Bergfuehrer.webp\",\"datePublished\":\"2026-01-26T18:06:13+00:00\",\"dateModified\":\"2026-02-12T20:07:03+00:00\",\"description\":\"Gef\u00fchrte Touren auf die Gipfel der Drei Zinnen. Gro\u00dfe Zinne Normalweg, Kleine Zinne und Westliche Zinne mit Bergf\u00fchrer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Drei-Zinnen-Blick-Bergfuehrer.webp\",\"contentUrl\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Drei-Zinnen-Blick-Bergfuehrer.webp\",\"width\":4032,\"height\":3024,\"caption\":\"Drei Zinnen Nordw\u00e4nde Klettern ausblick\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/drei-zinnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thomasgianola.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drei Zinnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#website\",\"url\":\"https:\\\/\\\/thomasgianola.com\\\/\",\"name\":\"Thomas Gianola Bergf\u00fchrer - mountainguide\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#\\\/schema\\\/person\\\/1eca9a4b029a522ad9c12bca4d072b52\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thomasgianola.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/#\\\/schema\\\/person\\\/1eca9a4b029a522ad9c12bca4d072b52\",\"name\":\"Thomas.gianola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp\",\"url\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp\",\"contentUrl\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp\",\"width\":2016,\"height\":1134,\"caption\":\"Thomas.gianola\"},\"logo\":{\"@id\":\"https:\\\/\\\/thomasgianola.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp\"},\"sameAs\":[\"https:\\\/\\\/thomasgianola.com\",\"https:\\\/\\\/www.facebook.com\\\/tgianola.mountainguide\",\"https:\\\/\\\/www.instagram.com\\\/thomas.gianola\\\/\"],\"url\":\"https:\\\/\\\/thomasgianola.com\\\/it\\\/author\\\/thomas-gianola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vie normali delle Tre Cime di Lavaredo con guida alpina","description":"Salite con la guida alpina alle cime delle Tre Cime. Salita alla Cima Grande, Cima Ovest e Cima Piccola con una guida alpina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thomasgianola.com\/it\/tre-cime\/","og_locale":"it_IT","og_type":"article","og_title":"Drei Zinnen Normalwege mit Bergf\u00fchrer","og_description":"Gef\u00fchrte Touren auf die Gipfel der Drei Zinnen. Gro\u00dfe Zinne Normalweg, Kleine Zinne und Westliche Zinne mit Bergf\u00fchrer.","og_url":"https:\/\/thomasgianola.com\/it\/tre-cime\/","og_site_name":"Thomas Gianola Bergf\u00fchrer Dolomiten","article_publisher":"https:\/\/www.facebook.com\/tgianola.mountainguide","article_author":"https:\/\/www.facebook.com\/tgianola.mountainguide","article_published_time":"2026-01-26T18:06:13+00:00","article_modified_time":"2026-02-12T20:07:03+00:00","og_image":[{"width":4032,"height":3024,"url":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Drei-Zinnen-Blick-Bergfuehrer.webp","type":"image\/webp"}],"author":"Thomas.gianola","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Thomas.gianola","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thomasgianola.com\/drei-zinnen\/#article","isPartOf":{"@id":"https:\/\/thomasgianola.com\/drei-zinnen\/"},"author":{"name":"Thomas.gianola","@id":"https:\/\/thomasgianola.com\/#\/schema\/person\/1eca9a4b029a522ad9c12bca4d072b52"},"headline":"Drei Zinnen","datePublished":"2026-01-26T18:06:13+00:00","dateModified":"2026-02-12T20:07:03+00:00","mainEntityOfPage":{"@id":"https:\/\/thomasgianola.com\/drei-zinnen\/"},"wordCount":3270,"commentCount":0,"publisher":{"@id":"https:\/\/thomasgianola.com\/#\/schema\/person\/1eca9a4b029a522ad9c12bca4d072b52"},"image":{"@id":"https:\/\/thomasgianola.com\/drei-zinnen\/#primaryimage"},"thumbnailUrl":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Drei-Zinnen-Blick-Bergfuehrer.webp","keywords":["bergf\u00fchrer","dolomiten","drei zinnen","normalwege"],"articleSection":["Dolomiten-Normalwege"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thomasgianola.com\/drei-zinnen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thomasgianola.com\/drei-zinnen\/","url":"https:\/\/thomasgianola.com\/drei-zinnen\/","name":"Vie normali delle Tre Cime di Lavaredo con guida alpina","isPartOf":{"@id":"https:\/\/thomasgianola.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thomasgianola.com\/drei-zinnen\/#primaryimage"},"image":{"@id":"https:\/\/thomasgianola.com\/drei-zinnen\/#primaryimage"},"thumbnailUrl":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Drei-Zinnen-Blick-Bergfuehrer.webp","datePublished":"2026-01-26T18:06:13+00:00","dateModified":"2026-02-12T20:07:03+00:00","description":"Salite con la guida alpina alle cime delle Tre Cime. Salita alla Cima Grande, Cima Ovest e Cima Piccola con una guida alpina.","breadcrumb":{"@id":"https:\/\/thomasgianola.com\/drei-zinnen\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thomasgianola.com\/drei-zinnen\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/thomasgianola.com\/drei-zinnen\/#primaryimage","url":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Drei-Zinnen-Blick-Bergfuehrer.webp","contentUrl":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/01\/Drei-Zinnen-Blick-Bergfuehrer.webp","width":4032,"height":3024,"caption":"Drei Zinnen Nordw\u00e4nde Klettern ausblick"},{"@type":"BreadcrumbList","@id":"https:\/\/thomasgianola.com\/drei-zinnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thomasgianola.com\/"},{"@type":"ListItem","position":2,"name":"Drei Zinnen"}]},{"@type":"WebSite","@id":"https:\/\/thomasgianola.com\/#website","url":"https:\/\/thomasgianola.com\/","name":"Thomas Gianola Guida alpina - mountainguide","description":"","publisher":{"@id":"https:\/\/thomasgianola.com\/#\/schema\/person\/1eca9a4b029a522ad9c12bca4d072b52"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thomasgianola.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/thomasgianola.com\/#\/schema\/person\/1eca9a4b029a522ad9c12bca4d072b52","name":"Tommaso.gianola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/02\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp","url":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/02\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp","contentUrl":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/02\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp","width":2016,"height":1134,"caption":"Thomas.gianola"},"logo":{"@id":"https:\/\/thomasgianola.com\/wp-content\/uploads\/2026\/02\/Thomas-Gianola-Bergfuehrer-Palagruppe.webp"},"sameAs":["https:\/\/thomasgianola.com","https:\/\/www.facebook.com\/tgianola.mountainguide","https:\/\/www.instagram.com\/thomas.gianola\/"],"url":"https:\/\/thomasgianola.com\/it\/author\/thomas-gianola\/"}]}},"_links":{"self":[{"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/posts\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":22,"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/posts\/470\/revisions"}],"predecessor-version":[{"id":1341,"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/posts\/470\/revisions\/1341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/media\/541"}],"wp:attachment":[{"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/media?parent=470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/categories?post=470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thomasgianola.com\/it\/wp-json\/wp\/v2\/tags?post=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}